{"id":27441,"date":"2026-08-24T12:38:36","date_gmt":"2026-08-24T16:38:36","guid":{"rendered":"https:\/\/centaurtheatre.com\/?post_type=centaur_event&#038;p=27441"},"modified":"2026-08-25T13:10:17","modified_gmt":"2026-08-25T17:10:17","slug":"confabulation-presente-bookmarked","status":"publish","type":"centaur_event","link":"https:\/\/centaurtheatre.com\/fr\/shows\/confabulation-presente-bookmarked\/","title":{"rendered":"Confabulation pr\u00e9sente: Bookmarked"},"content":{"rendered":"\n<p class=\"has-h-3-font-size wp-block-paragraph\"><\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>\u00a0\u00bb\u00a0<em>Nous nous trouvons tous dans la m\u00eame ville, nous sommes tous ensemble dans le monde et nous reconnaissons les similitudes et les diff\u00e9rences des uns et des autres. Et le fait de vivre cette exp\u00e9rience, de voir d\u2019autres personnes vous reconna\u00eetre et se connecter avec vous, c\u2019est quelque chose de vraiment puissant<\/em>.\u00a0\u00ab\u00a0<\/em><\/p>\n<cite>Matt Goldberg, via CBC<\/cite><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c0 propos du spectacle<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Notre th\u00e8me est \u00ab Marqu\u00e9 \u00bb : des histoires pleines de rebondissements, de personnages forts et de r\u00e9cits inoubliables. Ce sont des histoires qui parlent d&rsquo;histoires : des r\u00e9cits authentiques o\u00f9 une \u0153uvre litt\u00e9raire joue un r\u00f4le central. Comme un p\u00e9riple \u00e0 travers l&rsquo;Europe avec un exemplaire us\u00e9 des Mis\u00e9rables, une crise de la quarantaine travers\u00e9e avec Tolsto\u00ef \u00e0 port\u00e9e de main, ou ce po\u00e8me slam qui a boulevers\u00e9 votre vie.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-h-3-font-size\">Des histoires, aussi vraies que possible<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Confabulation est un \u00e9v\u00e9nement de narration en direct bas\u00e9 sur des histoires vraies. Chaque mois, nos conteurs invit\u00e9s partagent leurs r\u00e9cits autobiographiques autour d\u2019un th\u00e8me, sans notes, sans accessoires, ni artifices. Les histoires sont dr\u00f4les, r\u00e9fl\u00e9chies, d\u00e9chirantes et surtout honn\u00eates.<br>Mensuel au Th\u00e9\u00e2tre Centaur, Centre Phi, Mainline et autres lieux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.confabulation.ca\/\">www.confabulation.<\/a><a href=\"https:\/\/www.confabulation.ca\/\" target=\"_blank\" rel=\"noreferrer noopener\">ca<\/a><\/p>\n\n\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Confabulation, la s\u00e9rie montr\u00e9alaise originale de r\u00e9cits de vie, lance sa 17e saison avec une nouvelle soir\u00e9e d&rsquo;histoires.<\/p>\n","protected":false},"featured_media":27440,"template":"","class_list":["post-27441","centaur_event","type-centaur_event","status-publish","has-post-thumbnail","hentry","event-category-spectacle-invite"],"acf":[],"_links":{"self":[{"href":"https:\/\/centaurtheatre.com\/fr\/wp-json\/wp\/v2\/centaur_event\/27441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centaurtheatre.com\/fr\/wp-json\/wp\/v2\/centaur_event"}],"about":[{"href":"https:\/\/centaurtheatre.com\/fr\/wp-json\/wp\/v2\/types\/centaur_event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centaurtheatre.com\/fr\/wp-json\/wp\/v2\/media\/27440"}],"wp:attachment":[{"href":"https:\/\/centaurtheatre.com\/fr\/wp-json\/wp\/v2\/media?parent=27441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}